{"id":1155,"date":"2025-07-02T17:09:19","date_gmt":"2025-07-02T10:09:19","guid":{"rendered":"https:\/\/jdbbank.com.la\/?page_id=1155"},"modified":"2025-08-01T14:36:22","modified_gmt":"2025-08-01T07:36:22","slug":"cards","status":"publish","type":"page","link":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/","title":{"rendered":"ATM Cards Services"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"cz_gap clr\" style=\"height: 25px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/visa-debit-contactless\/\" title=\"Visa Debit Contactless\" role=\"button\" tabindex=\"0\" aria-label=\"Visa Debit Contactless\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_46452\" class=\"cz_46452 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-02_resize-1.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_105670\" class=\"cz_105670 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 VISA<\/h5>\n<h3>Visa Debit Contactless<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_65640\" class=\"cz_65640 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0ea5\u0ea7\u0ea1 3 \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9 \u0ec3\u0e99 1 \u0e9a\u0eb1\u0e94 \u0e84\u0eb7: \u0e9c\u0ec8\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a \u0ec1\u0e97\u0e9a\u0ec1\u0ea1\u0ec8\u0ec0\u0ea5\u0eb1\u0e81, Chip \u0ec1\u0ea5\u0eb0<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a Contactless Payment \u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 \u0e97\u0eb5\u0eae\u0ead\u0e87\u0e9a\u0eb1\u0e94 Contactless<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88, \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec1\u0ea5\u0eb0 \u0e9c\u0ec8\u0eb2\u0e99 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0ec4\u0e94\u0ec9<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d Plus \u0eab\u0ebc\u0eb7 VISA \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/visa-silver-card\/\" title=\"Visa Silver Card\" role=\"button\" tabindex=\"0\" aria-label=\"Visa Silver Card\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_14768\" class=\"cz_14768 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-07_resize.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_12238\" class=\"cz_12238 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 VISA<\/h5>\n<h3>Visa Silver Card<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_39909\" class=\"cz_39909 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e9c\u0ec8\u0eb2\u0e99 Online<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88, \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0ec4\u0e94\u0ec9<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d Plus \u0eab\u0ebc\u0eb7 VISA \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eae\u0eb1\u0e9a\u0eaa\u0ec8\u0ea7\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0e88\u0eb2\u0e81\u0eae\u0ec9\u0eb2\u0e99 \u0e84\u0ec9\u0eb2\u0e9e\u0eb2\u0e8d\u0ec3\u0e99 \u0ec1\u0ea5\u0eb0 \u0e95\u0ec8\u0eb2\u0e87\u0e9b\u0eb0\u0ec0\u0e97\u0e94<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/visa-gold-card\/\" title=\"Visa Gold Card\" role=\"button\" tabindex=\"0\" aria-label=\"Visa Gold Card\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_38520\" class=\"cz_38520 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-06_resize.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_16689\" class=\"cz_16689 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 VISA<\/h5>\n<h3>Visa Gold Card<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_41959\" class=\"cz_41959 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e9c\u0ec8\u0eb2\u0e99 Online<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88, \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0ec4\u0e94\u0ec9<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d Plus \u0eab\u0ebc\u0eb7 VISA \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eae\u0eb1\u0e9a\u0eaa\u0ec8\u0ea7\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0e88\u0eb2\u0e81\u0eae\u0ec9\u0eb2\u0e99 \u0e84\u0ec9\u0eb2\u0e9e\u0eb2\u0e8d\u0ec3\u0e99 \u0ec1\u0ea5\u0eb0 \u0e95\u0ec8\u0eb2\u0e87\u0e9b\u0eb0\u0ec0\u0e97\u0e94<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/visa-champa-super-gold\/\" title=\"Visa Champa Super Gold\" role=\"button\" tabindex=\"0\" aria-label=\"Visa Champa Super Gold\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_24403\" class=\"cz_24403 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-10_resize.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_80040\" class=\"cz_80040 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 VISA<\/h5>\n<h3>\u0e9a\u0eb1\u0e94\u0ec0\u0e84\u0ea3\u0e94\u0eb4\u0e94\u0ea7\u0eb5\u0e8a\u0ec8\u0eb2 Visa Champa Super Gold<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_70215\" class=\"cz_70215 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0ec0\u0e84\u0ebb\u0ec9\u0eb2\u0ec0\u0e95\u0eb5 Check \u2013 In \u0e9e\u0eb4\u0ec0\u0eaa\u0e94<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>Priority Boarding \u0eaa\u0eb4\u0e94\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e82\u0eb6\u0ec9\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0e9a\u0eb4\u0e99\u0e81\u0ec8\u0ead\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>Bag Loading Weight ( Economy ) \u2013 \u0ec0\u0e9e\u0eb5\u0ec8\u0ea1 05 Kg<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>Bag Loading Weight ( Business ) \u2013 \u0ec0\u0e9e\u0eb5\u0ec8\u0ea1 10Kg<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eab\u0ec9\u0ead\u0e87 Lounge \u0ec4\u0e94\u0ec9 2 \u0ec0\u0e97\u0eb7\u0ec8\u0ead<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e84\u0eb8\u0ec9\u0ea1\u0e84\u0ead\u0e87\u0ead\u0eb8\u0e9b\u0eb0\u0e95\u0eb4\u0ec0\u0eab\u0e94 \u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 50,000,000 \u0e81\u0eb5\u0e9a<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-debit-contactless\/\" title=\"UnionPay Debit Contactless\" role=\"button\" tabindex=\"0\" aria-label=\"UnionPay Debit Contactless\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_86599\" class=\"cz_86599 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-04_resize.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_81365\" class=\"cz_81365 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 UnionPay<\/h5>\n<h3>UnionPay Debit Contactless<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_102792\" class=\"cz_102792 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0ea5\u0ea7\u0ea1 3 \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9 \u0ec3\u0e99 1 \u0e9a\u0eb1\u0e94 \u0e84\u0eb7: \u0e9c\u0ec8\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0ec1\u0e97\u0e9a\u0ec1\u0ea1\u0ec8\u0ec0\u0ea5\u0eb1\u0e81, Chip \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0ec1\u0e95\u0eb0\u0e88\u0ec8\u0eb2\u0e8d (Contactless)<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a Contactless Payment (\u0e81\u0eb2\u0e99\u0e99\u0ecd\u0eb2\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e8a\u0ecd\u0eb2\u0ea5\u0eb0\u0ec1\u0e9a\u0e9a\u0ec1\u0e95\u0eb0\u0e88\u0ec8\u0eb2\u0e8d) \u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 \u0e97\u0eb5\u0eae\u0ead\u0e87\u0e9a\u0eb1\u0e94<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88 \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec4\u0e94\u0ec9<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d UnionPay \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-gold-card\/\" title=\"UnionPay Gold Card\" role=\"button\" tabindex=\"0\" aria-label=\"UnionPay Gold Card\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_67148\" class=\"cz_67148 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-09_resize.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_54752\" class=\"cz_54752 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 UnionPay<\/h5>\n<h3>UnionPay Gold Card<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_101315\" class=\"cz_101315 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9 \u0ec3\u0e99 1 \u0e9a\u0eb1\u0e94 \u0e84\u0eb7: \u0e9c\u0ec8\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a \u0ec1\u0e97\u0e9a\u0ec1\u0ea1\u0ec8\u0ec0\u0ea5\u0eb1\u0e81 \u0ec1\u0ea5\u0eb0 Chip<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a Payment \u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 \u0e97\u0eb5\u0eae\u0ead\u0e87\u0e9a\u0eb1\u0e94 EDC<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88, \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0ec4\u0e94\u0ec9<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d UnionPay \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a class=\"cz_content_box_link\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-platinum-card\/\" title=\"UnionPay Platinum Card\" role=\"button\" tabindex=\"0\" aria-label=\"UnionPay Platinum Card\"><div class=\"cz_eqh cz_content_box_parent_fx\"><div id=\"cz_101264\" class=\"cz_101264 cz_content_box clr cz_split_box_top cz_box_hide_arrow\"><div class=\"cz_split_box\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/All-Cards-JDB-08_resize.png\" alt=\"#\" \/><\/div><div class=\"cz_box_front clr\"><div class=\"cz_box_front_inner clr\"><div><div id=\"cz_47814\" class=\"cz_47814 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h5>\u0e9a\u0eb1\u0e94 UnionPay<\/h5>\n<h3>UnionPay Platinum Card<\/h3>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 15px\"><\/div><div class=\"clr\"><ul id=\"cz_53880\" class=\"cz_53880 cz_stylish_list clr cz_sl_icon_hover_zoom_in\"><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9 \u0ec3\u0e99 1 \u0e9a\u0eb1\u0e94 \u0e84\u0eb7: \u0e9c\u0ec8\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a \u0ec1\u0e97\u0e9a\u0ec1\u0ea1\u0ec8\u0ec0\u0ea5\u0eb1\u0e81 \u0ec1\u0ea5\u0eb0 Chip<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a Payment \u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 \u0e97\u0eb5\u0eae\u0ead\u0e87\u0e9a\u0eb1\u0e94 EDC<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88, \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0ec4\u0e94\u0ec9<\/span><\/div><\/li><li class=\"clr\"><div class=\"cz_sl_icon\"><i class=\"fas fa-circle-check mr10\" ><\/i><\/div><div><span>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d UnionPay \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87<\/span><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/a><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"cz_gap clr\" style=\"height: 20px\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"\u0e9a\u0eb1\u0e94 VISA \u0e9a\u0eb1\u0e94 Visa Debit Contactless \u0ea5\u0ea7\u0ea1 3 \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9 \u0ec3\u0e99 1 \u0e9a\u0eb1\u0e94 \u0e84\u0eb7: \u0e9c\u0ec8\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a \u0ec1\u0e97\u0e9a\u0ec1\u0ea1\u0ec8\u0ec0\u0ea5\u0eb1\u0e81, Chip \u0ec1\u0ea5\u0eb0\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a Contactless","protected":false},"author":2,"featured_media":1159,"parent":1095,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1155","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94 - Joint Development Bank<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94 - Joint Development Bank\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/\" \/>\n<meta property=\"og:site_name\" content=\"Joint Development Bank\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jdbbanklaos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T07:36:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/Cover-Card-01-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/\",\"name\":\"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94 - Joint Development Bank\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cover-Card-01-scaled-1.jpg\",\"datePublished\":\"2025-07-02T10:09:19+00:00\",\"dateModified\":\"2025-08-01T07:36:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cover-Card-01-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cover-Card-01-scaled-1.jpg\",\"width\":2560,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jdbbank.com.la\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e9a\u0eb8\u0e81\u0e84\u0ebb\u0e99\",\"item\":\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#website\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/\",\"name\":\"Joint Development Bank\",\"description\":\"\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2 \u0ea1\u0eb0\u0eab\u0eb2\u0e8a\u0ebb\u0e99 \u0ec0\u0e95\u0eb5\u0e9a\u0ec3\u0eab\u0e8d\u0ec8\u0ec4\u0e9b\u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0eb1\u0e99\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#organization\"},\"alternateName\":\"\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2 \u0ea1\u0eb0\u0eab\u0eb2\u0e8a\u0ebb\u0e99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jdbbank.com.la\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#organization\",\"name\":\"Joint Development Bank\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-jdb-s-300x140-1.png\",\"contentUrl\":\"https:\\\/\\\/jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-jdb-s-300x140-1.png\",\"width\":300,\"height\":140,\"caption\":\"Joint Development Bank\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jdbbanklaos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCO8s9-_LX75irlBE9duhBqQ\\\/featured?view_as=subscriber\",\"https:\\\/\\\/www.instagram.com\\\/jdbbanklaos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94 - Joint Development Bank","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/","og_locale":"en_US","og_type":"article","og_title":"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94 - Joint Development Bank","og_url":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/","og_site_name":"Joint Development Bank","article_publisher":"https:\/\/www.facebook.com\/jdbbanklaos\/","article_modified_time":"2025-08-01T07:36:22+00:00","og_image":[{"width":2560,"height":675,"url":"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/Cover-Card-01-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/","url":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/","name":"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94 - Joint Development Bank","isPartOf":{"@id":"https:\/\/www.jdbbank.com.la\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/#primaryimage"},"image":{"@id":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/Cover-Card-01-scaled-1.jpg","datePublished":"2025-07-02T10:09:19+00:00","dateModified":"2025-08-01T07:36:22+00:00","breadcrumb":{"@id":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/#primaryimage","url":"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/Cover-Card-01-scaled-1.jpg","contentUrl":"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/07\/Cover-Card-01-scaled-1.jpg","width":2560,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jdbbank.com.la\/"},{"@type":"ListItem","position":2,"name":"\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e9a\u0eb8\u0e81\u0e84\u0ebb\u0e99","item":"https:\/\/www.jdbbank.com.la\/personal-banking\/"},{"@type":"ListItem","position":3,"name":"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94"}]},{"@type":"WebSite","@id":"https:\/\/www.jdbbank.com.la\/#website","url":"https:\/\/www.jdbbank.com.la\/","name":"Joint Development Bank","description":"Blooming Together","publisher":{"@id":"https:\/\/www.jdbbank.com.la\/#organization"},"alternateName":"\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2 \u0ea1\u0eb0\u0eab\u0eb2\u0e8a\u0ebb\u0e99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jdbbank.com.la\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.jdbbank.com.la\/#organization","name":"Joint Development Bank","url":"https:\/\/www.jdbbank.com.la\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jdbbank.com.la\/#\/schema\/logo\/image\/","url":"https:\/\/jdbbank.com.la\/wp-content\/uploads\/2025\/05\/logo-jdb-s-300x140-1.png","contentUrl":"https:\/\/jdbbank.com.la\/wp-content\/uploads\/2025\/05\/logo-jdb-s-300x140-1.png","width":300,"height":140,"caption":"Joint Development Bank"},"image":{"@id":"https:\/\/www.jdbbank.com.la\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jdbbanklaos\/","https:\/\/www.youtube.com\/channel\/UCO8s9-_LX75irlBE9duhBqQ\/featured?view_as=subscriber","https:\/\/www.instagram.com\/jdbbanklaos\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/comments?post=1155"}],"version-history":[{"count":13,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1155\/revisions"}],"predecessor-version":[{"id":2157,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1155\/revisions\/2157"}],"up":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/media\/1159"}],"wp:attachment":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/media?parent=1155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}