{"id":1405,"date":"2025-07-14T11:43:26","date_gmt":"2025-07-14T04:43:26","guid":{"rendered":"https:\/\/jdbbank.com.la\/?page_id=1405"},"modified":"2025-07-14T14:00:12","modified_gmt":"2025-07-14T07:00:12","slug":"unionpay-debit-contactless","status":"publish","type":"page","link":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-debit-contactless\/","title":{"rendered":"UnionPay Debit Contactless"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"cz_90070\" class=\"cz_90070 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h1 class=\"pb-3\">UnionPay Debit Contactless<\/h1>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 50px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"cz_92396\" class=\"cz_92396 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h3><span style=\"color: #3366ff;\"><strong>\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless:<\/strong><\/span><\/h3>\n<\/div><\/div><\/div><div class=\"relative\"><div id=\"cz_96587\" class=\"cz_96587 cz_line tac\"><\/div><\/div><div class=\"clr\"><\/div><div id=\"cz_84143\" class=\"cz_84143 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><p>\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless \u0ec0\u0e9b\u0eb1\u0e99\u0e9a\u0eb1\u0e94\u0ec3\u0e8a\u0ec9\u0ec1\u0e97\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94 \u0ec0\u0e8a\u0eb1\u0ec8\u0e99:\u0e96\u0ead\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94\u0e81\u0eb1\u0e9a\u0e95\u0eb9\u0ec9 ATM \u0ec1\u0ea5\u0eb0 \u0e8a\u0eb3\u0ea5\u0eb0\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0e88\u0eb3\u0e99\u0ea7\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0ec3\u0e99\u0e9a\u0eb1\u0e99\u0e8a\u0eb5\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81\u0e9b\u0eb0\u0ea2\u0eb1\u0e94\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0e8a\u0eb3\u0ea5\u0eb0\u0e84\u0ec8\u0eb2\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0ec6\u0e95\u0eb2\u0ea1\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0e97\u0eb5\u0ea1\u0eb5\u0eaa\u0eb1\u0e99\u0e8d\u0eb2\u0ea5\u0eb1\u0e81 Contactless \u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec1\u0e95\u0eb0\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e88\u0ec8\u0eb2\u0e8d \u0eab\u0ebc\u0eb7 \u0e8a\u0eb3\u0ea5\u0eb0\u200b\u0e9c\u0ec8\u0eb2\u0e99\u200b\u0ead\u0eb4\u0e99\u200b\u0ec0\u0e95\u0eb5\u200b\u0ec0\u0e99\u0eb1\u0e94. \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e96\u0ead\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94 \u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0ebb\u0ec8\u0ea7\u0ec2\u0ea5\u0e81\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d Union Pay. \u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ea5\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0eab\u0ea7\u0e82\u0ead\u0e87\u0e9a\u0eb1\u0e94\u0e9c\u0ec8\u0eb2\u0e99\u0e9a\u0eb1\u0e99\u0e8a\u0eb5\u0e9c\u0ec8\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec1\u0e88\u0ec9\u0e87\u0ec0\u0e95\u0eb7\u0ead\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e82\u0ecd\u0ec9\u0e84\u0ea7\u0eb2\u0ea1 SMS \u0ec1\u0ea5\u0eb0 Application JDB Yes \u0e82\u0ead\u0e87\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99 \u0e9e\u0ec9\u0ead\u0ea1\u0eae\u0eb1\u0e9a\u0eaa\u0ec8\u0ea7\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0e9e\u0eb4\u0ec0\u0eaa\u0e94 \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0e9a\u0eb1\u0e94 \u0eab\u0ebc\u0eb7 \u0ec3\u0e8a\u0ec9\u0e8a\u0eb3\u0ea5\u0eb0\u0e84\u0ec8\u0eb2\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0e95\u0eb2\u0ea1\u0eae\u0ec9\u0eb2\u0e99\u0e84\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eae\u0ec8\u0ea7\u0ea1\u0ec2\u0e84\u0e87\u0e81\u0eb2\u0e99 05% \u2013 10% \u0e81\u0eb1\u0e9a\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2.<\/p>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 30px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"cz_16557\" class=\"cz_16557 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h3><span style=\"color: #3366ff;\"><strong>\u0e9c\u0ebb\u0e99\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94\u0e97\u0eb5\u0ec8\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a:<\/strong><\/span><\/h3>\n<\/div><\/div><\/div><div class=\"relative\"><div id=\"cz_96587\" class=\"cz_96587 cz_line tac\"><\/div><\/div><div class=\"clr\"><\/div><div id=\"cz_26563\" class=\"cz_26563 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><ul>\n<li>\u0ea5\u0ea7\u0ea1 3 \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9 \u0ec3\u0e99 1 \u0e9a\u0eb1\u0e94 \u0e84\u0eb7: \u0e9c\u0ec8\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0ec1\u0e97\u0e9a\u0ec1\u0ea1\u0ec8\u0ec0\u0ea5\u0eb1\u0e81, Chip \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0ec1\u0e95\u0eb0\u0e88\u0ec8\u0eb2\u0e8d ( Contactless )<\/li>\n<li>\u0e8d\u0ebb\u0e81\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e9a\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a Contactless Payment ( \u0e81\u0eb2\u0e99\u0e99\u0ecd\u0eb2\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e8a\u0ecd\u0eb2\u0ea5\u0eb0\u0ec1\u0e9a\u0e9a\u0ec1\u0e95\u0eb0\u0e88\u0ec8\u0eb2\u0e8d ) \u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 \u0e97\u0eb5\u0eae\u0ead\u0e87\u0e9a\u0eb1\u0e94<\/li>\n<li>\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ea7\u0ec8\u0ead\u0e87\u0ec4\u0ea7, \u0e97\u0eb1\u0e99\u0ec3\u0e88 \u0ec1\u0ea5\u0eb0 \u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb3\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e87\u0eb4\u0e99.<\/li>\n<li>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e8a\u0eb7\u0ec9\u200b\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99 \u0e9c\u0ec8\u0eb2\u0e99 Internet \u0ec4\u0e94\u0ec9;<\/li>\n<li>\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u200b\u0ec3\u0e8a\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0ec4\u0e94\u0ec9\u0e97\u0eb8\u0e81\u0e88\u0eb8\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u200b\u0ec2\u0ea5\u0e81 \u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edd\u0eb2\u0e8d UnionPay \u0ec4\u0e94\u0ec9\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 24 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87;<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"cz_24184\" class=\"cz_24184 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h3><span style=\"color: #3366ff;\"><strong>\u0e84\u0ec8\u0eb2\u0e97\u0ecd\u0eb2\u0e99\u0ebd\u0ea1\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e9a\u0eb1\u0e94:<\/strong><\/span><\/h3>\n<\/div><\/div><\/div><div class=\"relative\"><div id=\"cz_96587\" class=\"cz_96587 cz_line tac\"><\/div><\/div><div class=\"clr\"><\/div><div id=\"cz_61742\" class=\"cz_61742 cz_title clr cz_title_pos_block\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><table border=\"1\" width=\"81%\">\n<tbody>\n<tr>\n<td width=\"48\"><span style=\"color: #3366ff;\"><strong>\u0ea5<\/strong><strong>\/<\/strong><strong>\u0e94<\/strong><\/span><\/td>\n<td width=\"259\"><span style=\"color: #3366ff;\"><strong>\u0ea5\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99<\/strong><\/span><\/td>\n<td width=\"239\"><span style=\"color: #3366ff;\"><strong>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"48\">1<\/td>\n<td width=\"259\">\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0e9a\u0eb1\u0e94\u0ec3\u0edd\u0ec8<\/td>\n<td width=\"239\">40,000\u0e81\u0eb5\u0e9a\/180\u0e9a\u0eb2\u0e94\/5\u0ec2\u0e94\u0ea5\u0eb2\/\u0e9a\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">2<\/td>\n<td width=\"259\">\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e9a\u0eb1\u0e94\u0ec3\u0edd\u0ec8<\/td>\n<td width=\"239\">20,000\u0e81\u0eb5\u0e9a\/100\u0e9a\u0eb2\u0e94\/3\u0ec2\u0e94\u0ea5\u0eb2\/\u0e9a\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">3<\/td>\n<td width=\"259\">\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0ea5\u0eb0\u0eab\u0eb1\u0e94\u0e9a\u0eb1\u0e94\u0ec3\u0edd\u0ec8<\/td>\n<td width=\"239\">10,000\u0e81\u0eb5\u0e9a\/50\u0e9a\u0eb2\u0e94\/2\u0ec2\u0e94\u0ea5\u0eb2<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">4<\/td>\n<td width=\"259\">\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0eb2\u0ea5\u0eb8\u0e87\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e9a\u0eb1\u0e94\/\u0ec0\u0e94\u0eb7\u0ead\u0e99<\/td>\n<td width=\"239\">5,000\u0e81\u0eb5\u0e9a\/25\u0e9a\u0eb2\u0e94\/0,6\u0ec2\u0e94\u0ea5\u0eb2<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">5<\/td>\n<td width=\"259\">\u0e84\u0ec8\u0eb2 SMS (\u0e9f\u0eb5\u0ea3 3 \u0e84\u0eb1\u0ec9\u0e87 \u0e95\u0ecd\u0ec8\u0ec0\u0e94\u0eb7\u0ead\u0e99)<\/td>\n<td width=\"239\">3.000 \u0e81\u0eb5\u0e9a\/ \u0ec0\u0e94\u0eb7\u0ead\u0e99<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">6<\/td>\n<td width=\"259\">\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94\u0e94\u0ec8\u0ea7\u0e99\u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0ea1\u0eb7\u0ec9\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0ea5\u0eb8\u0e81\u0e84\u0ec9\u0eb2 \u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87<\/td>\n<td width=\"239\">20\u0ec2\u0e94\u0ea5\u0eb2\/\u0e9a\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\" width=\"546\"><span style=\"color: #3366ff;\"><strong>\u0e84\u0ec8\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e96\u0ead\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9<\/strong><strong> ATM<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"48\">7<\/td>\n<td width=\"259\">\u0e96\u0ead\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM JDB<\/td>\n<td width=\"239\">\u0e9a\u0ecd\u0ec8\u0ec0\u0e81\u0eb1\u0e9a<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">8<\/td>\n<td width=\"259\">\u0e96\u0ead\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM \u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0ead\u0eb7\u0ec8\u0e99\u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0e9b\u0eb0\u0ec0\u0e97\u0e94 (LAPNet )<\/td>\n<td width=\"239\">2000 \u0e81\u0eb5\u0e9a\/\u0ea5\u0eb2\u0e8d\u0e81\u0eb2\u0e99<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">9<\/td>\n<td width=\"259\">\u0e96\u0ead\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0eb9\u0ec9 ATM &nbsp;\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0ead\u0eb7\u0ec8\u0e99\u0ec3\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0e9b\u0eb0\u0ec0\u0e97\u0e94<\/td>\n<td width=\"239\">\u0e9a\u0ecd\u0ec8\u0ec0\u0e81\u0eb1\u0e9a<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">10<\/td>\n<td width=\"259\">\u0e96\u0ead\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94\u0e9c\u0ec8\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eae\u0eb9\u0e94\u0e9a\u0eb1\u0e94 EDC \u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0ead\u0eb7\u0ec8\u0e99 \u0e9e\u0eb2\u0e8d\u0ec3\u0e99 \u0ec1\u0ea5\u0eb0 \u0e95\u0ec8\u0eb2\u0e87\u0e9b\u0eb0\u0ec0\u0e97\u0e94<\/td>\n<td width=\"239\">\u0e9a\u0ecd\u0ec8\u0ec0\u0e81\u0eb1\u0e9a<\/td>\n<\/tr>\n<tr>\n<td width=\"48\">11<\/td>\n<td width=\"259\">\u0ec3\u0e8a\u0ec9\u0e9a\u0eb1\u0e94\u0ec0\u0e94\u0e9a\u0eb4\u0e94 UPI JDB&nbsp; \u0e8a\u0eb7\u0ec9\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0e95\u0eb2\u0ea1\u0eae\u0ec9\u0eb2\u0e99\u0e84\u0ec9\u0eb2 EDC \u0e82\u0ead\u0e87\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99 JDB \u0ec1\u0ea5\u0eb0 \u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0ead\u0eb7\u0ec8\u0e99\/ Online Shopping \/ \u0e84\u0eb1\u0ec9\u0e87<\/td>\n<td width=\"239\">\u0e9a\u0ecd\u0ec8\u0ec0\u0e81\u0eb1\u0e9a<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div><\/div><div class=\"cz_gap clr\" style=\"height: 30px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"cz_29749\" class=\"cz_29749 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h3><span style=\"color: #3366ff;\"><strong>\u0ec0\u0e87\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0e82\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0edd\u0eb1\u0e81:<\/strong><\/span><\/h3>\n<\/div><\/div><\/div><div class=\"relative\"><div id=\"cz_96587\" class=\"cz_96587 cz_line tac\"><\/div><\/div><div class=\"clr\"><\/div><div id=\"cz_60082\" class=\"cz_60082 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><ol>\n<li><strong>\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0edd\u0eb1\u0e81\u0e9a\u0eb1\u0e94:<\/strong>\n<ul>\n<li>\u0ec0\u0e9b\u0eb5\u0e94\u0e9a\u0eb1\u0e99\u0e8a\u0eb5\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ec8\u0eb3 100,000 \u0e81\u0eb5\u0e9a, 500 \u0e9a\u0eb2\u0e94, 20 \u0ec2\u0e94\u0ea5\u0eb2<\/li>\n<li>\u0ec0\u0e9b\u0eb5\u0e94\u0e9a\u0eb1\u0e99\u0e8a\u0eb5\u0ec4\u0e94\u0ec9 3 \u0eaa\u0eb0\u0e81\u0eb8\u0e99\u0ec0\u0e87\u0eb4\u0e99: \u0e81\u0eb4\u0e9a, \u0e9a\u0eb2\u0e94,\u0ec2\u0e94\u0ea5\u0eb2<\/li>\n<\/ul>\n<\/li>\n<li><strong>\u0e9c\u0eb9\u0ec9\u0ea1\u0eb5\u0e9e\u0eb9\u0ea1\u0ea5\u0ecd\u0eb2\u0ec0\u0e99\u0ebb\u0eb2\u0ea2\u0eb9\u0ec8 \u0eaa\u0e9b\u0e9b \u0ea5\u0eb2\u0ea7:<\/strong>\n<ul>\n<li>\u0eaa\u0ecd\u0eb2\u0ec0\u0e99\u0ebb\u0eb2\u0e9b\u0eb6\u0ec9\u0ea1\u0eaa\u0eb3\u0ea1\u0eb0\u0ec2\u0e99\u0e84\u0ebb\u0ea7 ( Family book ), \u0e9a\u0eb1\u0e94\u0e9b\u0eb0\u0e88\u0ecd\u0eb2\u0e95\u0ebb\u0ea7 (ID) \u0eab\u0ebc\u0eb7 \u0edc\u0eb1\u0e87\u0eaa\u0eb7\u0e9c\u0ec8\u0eb2\u0e99\u0ec1\u0e94\u0e99 (Passport) \u0e97\u0eb5\u0ec8\u0e8d\u0eb1\u0e87\u0e9a\u0ecd\u0ecd\u0ec8\u0edd\u0ebb\u0e94\u0ead\u0eb2\u0e8d\u0eb8;<\/li>\n<li>\u0ec0\u0e9a\u0eb5\u0ec2\u0e97\u0ea5\u0eb0\u0eaa\u0eb1\u0e9a \u0ec1\u0ea5\u0eb0 \u0ead\u0eb5\u0ec0\u0ea1\u0ea7 \u0e82\u0ead\u0e87\u0e9c\u0eb9\u0ec9\u0eaa\u0eb0\u0edd\u0eb1\u0e81\u0e9a\u0eb1\u0e94;<\/li>\n<li>\u0e9c\u0eb9\u0ec9\u0eaa\u0eb0\u0edd\u0eb1\u0e81\u0e9a\u0eb1\u0e94 \u0e95\u0ec9\u0ead\u0e87\u0ea1\u0eb5\u0ead\u0eb2\u0e8d\u0eb8 15 \u0e9b\u0eb5\u0e82\u0eb6\u0ec9\u0e99\u0ec4\u0e9b.<\/li>\n<\/ul>\n<\/li>\n<li><strong>\u0e9c\u0eb9\u0ec9\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e9e\u0eb9\u0ea1\u0ea5\u0ecd\u0eb2\u0ec0\u0e99\u0ebb\u0eb2\u0ea2\u0eb9\u0ec8 \u0eaa\u0e9b\u0e9b \u0ea5\u0eb2\u0ea7:<\/strong>\n<ul>\n<li>\u0eaa\u0ecd\u0eb2\u0ec0\u0e99\u0ebb\u0eb2\u0edc\u0eb1\u0e87\u0eaa\u0eb7\u0e9c\u0ec8\u0eb2\u0e99\u0ec1\u0e94\u0e99 (Passport) \u0e97\u0eb5\u0ec8\u0e8d\u0eb1\u0e87\u0e9a\u0ecd\u0ecd\u0ec8\u0edd\u0ebb\u0e94\u0ead\u0eb2\u0e8d\u0eb8;<\/li>\n<li>\u0e95\u0ec9\u0ead\u0e87\u0ea1\u0eb5\u0e9a\u0eb8\u0e81\u0e84\u0ebb\u0e99 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94 \u0e97\u0eb5\u0ec8\u0e9c\u0eb9\u0ec9\u0e81\u0ec8\u0ebd\u0ea7\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0ea2\u0eb9\u0ec8\u0e84\u0ecd\u0ec9\u0eb2\u0e9b\u0eb0\u0e81\u0eb1\u0e99 \u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e8a\u0ecd\u0eb2\u0ea5\u0eb0\u0edc\u0eb5\u0ec9;<\/li>\n<li>\u0ec3\u0e9a\u0ead\u0eb0\u0e99\u0eb8\u0e8d\u0eb2\u0e94\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0ea2\u0eb9\u0ec8 \u0eaa\u0e9b\u0e9b \u0ea5\u0eb2\u0ea7 (work permit);<\/li>\n<li>\u0ec0\u0e9a\u0eb5\u0ec2\u0e97\u0ea5\u0eb0\u0eaa\u0eb1\u0e9a \u0ec1\u0ea5\u0eb0 \u0ead\u0eb5\u0ec0\u0ea1\u0ea7 \u0e82\u0ead\u0e87\u0e9c\u0eb9\u0ec9\u0eaa\u0eb0\u0edd\u0eb1\u0e81\u0e9a\u0eb1\u0e94;<\/li>\n<li>\u0e9c\u0eb9\u0ec9\u0eaa\u0eb0\u0edd\u0eb1\u0e81\u0e9a\u0eb1\u0e94 \u0e95\u0ec9\u0ead\u0e87\u0ea1\u0eb5\u0ead\u0eb2\u0e8d\u0eb8 15 \u0e9b\u0eb5\u0e82\u0eb6\u0ec9\u0e99\u0ec4\u0e9b.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"cz_39072\" class=\"cz_39072 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><h3><strong>\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0ead\u0e94\u0ec4\u0e9e\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e8a\u0eb3\u0ea5\u0eb0\u0e9c\u0ec8\u0eb2\u0e99 Online<\/strong><\/h3>\n<\/div><\/div><\/div><div class=\"relative\"><div id=\"cz_96587\" class=\"cz_96587 cz_line tac\"><\/div><\/div><div class=\"clr\"><\/div><div id=\"cz_106082\" class=\"cz_106082 cz_title clr cz_title_pos_inline\"><div class=\"cz_title_content\"><div class=\"cz_wpe_content\"><ul>\n<li>\u0ea1\u0eb5\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a <strong>Upop <\/strong>\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0ead\u0e94\u0ec4\u0e9e \u0ec3\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0ecd\u0eb2\u0e8a\u0ecd\u0eb2\u0ea5\u0eb0\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e95\u0ec8\u0eb2\u0e87\u0ec6 \u0e9c\u0ec8\u0eb2\u0e99\u0e8a\u0ec8\u0ead\u0e87\u0e97\u0eb2\u0e87\u0ead\u0eb4\u0e99\u0ec0\u0e95\u0eb5\u0ec0\u0e99\u0eb1\u0e94 (Online) \u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e9c\u0eb9\u0ec9\u0e96\u0eb7\u0e9a\u0eb1\u0e94 Union Pay Credit &amp; Debit \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9b\u0eb1\u0e99\u0e9a\u0eb1\u0e94 Chip \u0e97\u0eb5\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99\u0e88\u0eb2\u0e81 EMVco \u0ec3\u0e99\u0eaa\u0eb2\u0e81\u0ebb\u0e99.<\/li>\n<li>\u0e96\u0ec9\u0eb2\u0eab\u0eb2\u0e81\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e9c\u0eb9\u0ec9\u0e96\u0eb7\u0e9a\u0eb1\u0e94\u0e9c\u0eb8\u0ec9\u0ec3\u0e94\u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0ea5\u0eb0\u0eab\u0eb1\u0e94 OTP \u0ec1\u0ea1\u0ec8\u0e99\u0e88\u0eb0\u0e95\u0ec9\u0ead\u0e87\u0ec3\u0eab\u0ec9\u0e9c\u0eb9\u0ec9\u0e96\u0eb7\u0e9a\u0eb1\u0e94\u0ec2\u0e97\u0e95\u0eb4\u0e94\u0e95\u0ecd\u0ec8 \u0ec0\u0e9a\u0eb5 <strong>1499<\/strong><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"UnionPay Debit Contactless \u0e9a\u0eb1\u0e94 UnionPay Debit Contactless: \u0e9a\u0eb1\u0e94 UnionPay Debit Contactless \u0ec0\u0e9b\u0eb1\u0e99\u0e9a\u0eb1\u0e94\u0ec3\u0e8a\u0ec9\u0ec1\u0e97\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94 \u0ec0\u0e8a\u0eb1\u0ec8\u0e99:\u0e96\u0ead\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0eaa\u0ebb\u0e94\u0e81\u0eb1\u0e9a\u0e95\u0eb9\u0ec9 ATM \u0ec1\u0ea5\u0eb0 \u0e8a\u0eb3\u0ea5\u0eb0\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0e88\u0eb3\u0e99\u0ea7\u0e99\u0ec0\u0e87\u0eb4\u0e99\u0ec3\u0e99\u0e9a\u0eb1\u0e99\u0e8a\u0eb5\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81\u0e9b\u0eb0\u0ea2\u0eb1\u0e94\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0e8a\u0eb3\u0ea5\u0eb0\u0e84\u0ec8\u0eb2\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7","protected":false},"author":2,"featured_media":0,"parent":1155,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1405","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless - Joint Development Bank<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-debit-contactless\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless - Joint Development Bank\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-debit-contactless\/\" \/>\n<meta property=\"og:site_name\" content=\"Joint Development Bank\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jdbbanklaos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T07:00:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/08\/jdb_building-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/cards\\\/unionpay-debit-contactless\\\/\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/cards\\\/unionpay-debit-contactless\\\/\",\"name\":\"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless - Joint Development Bank\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#website\"},\"datePublished\":\"2025-07-14T04:43:26+00:00\",\"dateModified\":\"2025-07-14T07:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/cards\\\/unionpay-debit-contactless\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/cards\\\/unionpay-debit-contactless\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/cards\\\/unionpay-debit-contactless\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jdbbank.com.la\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e9a\u0eb8\u0e81\u0e84\u0ebb\u0e99\",\"item\":\"https:\\\/\\\/www.jdbbank.com.la\\\/personal-banking\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94\",\"item\":\"https:\\\/\\\/www.jdbbank.com.la\\\/en\\\/personal-banking\\\/cards\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#website\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/\",\"name\":\"Joint Development Bank\",\"description\":\"\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2 \u0ea1\u0eb0\u0eab\u0eb2\u0e8a\u0ebb\u0e99 \u0ec0\u0e95\u0eb5\u0e9a\u0ec3\u0eab\u0e8d\u0ec8\u0ec4\u0e9b\u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0eb1\u0e99\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#organization\"},\"alternateName\":\"\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2 \u0ea1\u0eb0\u0eab\u0eb2\u0e8a\u0ebb\u0e99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jdbbank.com.la\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#organization\",\"name\":\"Joint Development Bank\",\"url\":\"https:\\\/\\\/www.jdbbank.com.la\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-jdb-s-300x140-1.png\",\"contentUrl\":\"https:\\\/\\\/jdbbank.com.la\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-jdb-s-300x140-1.png\",\"width\":300,\"height\":140,\"caption\":\"Joint Development Bank\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jdbbank.com.la\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jdbbanklaos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCO8s9-_LX75irlBE9duhBqQ\\\/featured?view_as=subscriber\",\"https:\\\/\\\/www.instagram.com\\\/jdbbanklaos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless - Joint Development Bank","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-debit-contactless\/","og_locale":"en_US","og_type":"article","og_title":"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless - Joint Development Bank","og_url":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/unionpay-debit-contactless\/","og_site_name":"Joint Development Bank","article_publisher":"https:\/\/www.facebook.com\/jdbbanklaos\/","article_modified_time":"2025-07-14T07:00:12+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.jdbbank.com.la\/wp-content\/uploads\/2025\/08\/jdb_building-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jdbbank.com.la\/personal-banking\/cards\/unionpay-debit-contactless\/","url":"https:\/\/www.jdbbank.com.la\/personal-banking\/cards\/unionpay-debit-contactless\/","name":"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless - Joint Development Bank","isPartOf":{"@id":"https:\/\/www.jdbbank.com.la\/#website"},"datePublished":"2025-07-14T04:43:26+00:00","dateModified":"2025-07-14T07:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.jdbbank.com.la\/personal-banking\/cards\/unionpay-debit-contactless\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jdbbank.com.la\/personal-banking\/cards\/unionpay-debit-contactless\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jdbbank.com.la\/personal-banking\/cards\/unionpay-debit-contactless\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jdbbank.com.la\/"},{"@type":"ListItem","position":2,"name":"\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e9a\u0eb8\u0e81\u0e84\u0ebb\u0e99","item":"https:\/\/www.jdbbank.com.la\/personal-banking\/"},{"@type":"ListItem","position":3,"name":"\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e94","item":"https:\/\/www.jdbbank.com.la\/en\/personal-banking\/cards\/"},{"@type":"ListItem","position":4,"name":"\u0e9a\u0eb1\u0e94 UnionPay Debit Contactless"}]},{"@type":"WebSite","@id":"https:\/\/www.jdbbank.com.la\/#website","url":"https:\/\/www.jdbbank.com.la\/","name":"Joint Development Bank","description":"Blooming Together","publisher":{"@id":"https:\/\/www.jdbbank.com.la\/#organization"},"alternateName":"\u0e97\u0eb0\u0e99\u0eb2\u0e84\u0eb2\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e9e\u0eb1\u0e94\u0e97\u0eb0\u0e99\u0eb2 \u0ea1\u0eb0\u0eab\u0eb2\u0e8a\u0ebb\u0e99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jdbbank.com.la\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.jdbbank.com.la\/#organization","name":"Joint Development Bank","url":"https:\/\/www.jdbbank.com.la\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jdbbank.com.la\/#\/schema\/logo\/image\/","url":"https:\/\/jdbbank.com.la\/wp-content\/uploads\/2025\/05\/logo-jdb-s-300x140-1.png","contentUrl":"https:\/\/jdbbank.com.la\/wp-content\/uploads\/2025\/05\/logo-jdb-s-300x140-1.png","width":300,"height":140,"caption":"Joint Development Bank"},"image":{"@id":"https:\/\/www.jdbbank.com.la\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jdbbanklaos\/","https:\/\/www.youtube.com\/channel\/UCO8s9-_LX75irlBE9duhBqQ\/featured?view_as=subscriber","https:\/\/www.instagram.com\/jdbbanklaos\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":2,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1405\/revisions"}],"predecessor-version":[{"id":1409,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1405\/revisions\/1409"}],"up":[{"embeddable":true,"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/pages\/1155"}],"wp:attachment":[{"href":"https:\/\/www.jdbbank.com.la\/en\/wp-json\/wp\/v2\/media?parent=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}